{"id":620,"date":"2023-08-02T00:33:19","date_gmt":"2023-08-02T00:33:19","guid":{"rendered":"https:\/\/dornsife.usc.edu\/spatial\/?page_id=620"},"modified":"2026-06-04T16:57:03","modified_gmt":"2026-06-04T23:57:03","slug":"events","status":"publish","type":"page","link":"https:\/\/dornsife.usc.edu\/spatial\/events\/","title":{"rendered":"Events"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":207,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-event-listing.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-620","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Events - Spatial Sciences Institute<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dornsife.usc.edu\/spatial\/events\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Events - Spatial Sciences Institute\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dornsife.usc.edu\/spatial\/events\/\" \/>\n<meta property=\"og:site_name\" content=\"Spatial Sciences Institute\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-04T23:57:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dornsife.usc.edu\\\/spatial\\\/events\\\/\",\"url\":\"https:\\\/\\\/dornsife.usc.edu\\\/spatial\\\/events\\\/\",\"name\":\"Events - Spatial Sciences Institute\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dornsife.usc.edu\\\/spatial\\\/#website\"},\"datePublished\":\"2023-08-02T00:33:19+00:00\",\"dateModified\":\"2026-06-04T23:57:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dornsife.usc.edu\\\/spatial\\\/events\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dornsife.usc.edu\\\/spatial\\\/events\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dornsife.usc.edu\\\/spatial\\\/events\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dornsife.usc.edu\\\/spatial\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dornsife.usc.edu\\\/spatial\\\/#website\",\"url\":\"https:\\\/\\\/dornsife.usc.edu\\\/spatial\\\/\",\"name\":\"Spatial Sciences Institute\",\"description\":\"USC Dornsife Spatial Sciences Institute\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dornsife.usc.edu\\\/spatial\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Events - Spatial Sciences Institute","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dornsife.usc.edu\/spatial\/events\/","og_locale":"en_US","og_type":"article","og_title":"Events - Spatial Sciences Institute","og_url":"https:\/\/dornsife.usc.edu\/spatial\/events\/","og_site_name":"Spatial Sciences Institute","article_modified_time":"2026-06-04T23:57:03+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dornsife.usc.edu\/spatial\/events\/","url":"https:\/\/dornsife.usc.edu\/spatial\/events\/","name":"Events - Spatial Sciences Institute","isPartOf":{"@id":"https:\/\/dornsife.usc.edu\/spatial\/#website"},"datePublished":"2023-08-02T00:33:19+00:00","dateModified":"2026-06-04T23:57:03+00:00","breadcrumb":{"@id":"https:\/\/dornsife.usc.edu\/spatial\/events\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dornsife.usc.edu\/spatial\/events\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dornsife.usc.edu\/spatial\/events\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dornsife.usc.edu\/spatial\/"},{"@type":"ListItem","position":2,"name":"Events"}]},{"@type":"WebSite","@id":"https:\/\/dornsife.usc.edu\/spatial\/#website","url":"https:\/\/dornsife.usc.edu\/spatial\/","name":"Spatial Sciences Institute","description":"USC Dornsife Spatial Sciences Institute","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dornsife.usc.edu\/spatial\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/dornsife.usc.edu\/spatial\/wp-json\/wp\/v2\/pages\/620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dornsife.usc.edu\/spatial\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dornsife.usc.edu\/spatial\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dornsife.usc.edu\/spatial\/wp-json\/wp\/v2\/users\/207"}],"replies":[{"embeddable":true,"href":"https:\/\/dornsife.usc.edu\/spatial\/wp-json\/wp\/v2\/comments?post=620"}],"version-history":[{"count":53,"href":"https:\/\/dornsife.usc.edu\/spatial\/wp-json\/wp\/v2\/pages\/620\/revisions"}],"predecessor-version":[{"id":8158,"href":"https:\/\/dornsife.usc.edu\/spatial\/wp-json\/wp\/v2\/pages\/620\/revisions\/8158"}],"wp:attachment":[{"href":"https:\/\/dornsife.usc.edu\/spatial\/wp-json\/wp\/v2\/media?parent=620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}