{"id":1376,"date":"2023-04-12T18:49:20","date_gmt":"2023-04-12T18:49:20","guid":{"rendered":"https:\/\/dornsife.usc.edu\/physics\/?page_id=1376"},"modified":"2024-09-17T17:04:20","modified_gmt":"2024-09-17T17:04:20","slug":"staff","status":"publish","type":"page","link":"https:\/\/dornsife.usc.edu\/physics\/staff\/","title":{"rendered":"Staff"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-person-listing.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1376","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Staff - Department of Physics and Astronomy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dornsife.usc.edu\/physics\/staff\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Staff - Department of Physics and Astronomy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dornsife.usc.edu\/physics\/staff\/\" \/>\n<meta property=\"og:site_name\" content=\"Department of Physics and Astronomy\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-17T17:04:20+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dornsife.usc.edu\\\/physics\\\/staff\\\/\",\"url\":\"https:\\\/\\\/dornsife.usc.edu\\\/physics\\\/staff\\\/\",\"name\":\"Staff - Department of Physics and Astronomy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dornsife.usc.edu\\\/physics\\\/#website\"},\"datePublished\":\"2023-04-12T18:49:20+00:00\",\"dateModified\":\"2024-09-17T17:04:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dornsife.usc.edu\\\/physics\\\/staff\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dornsife.usc.edu\\\/physics\\\/staff\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dornsife.usc.edu\\\/physics\\\/staff\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dornsife.usc.edu\\\/physics\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Staff\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dornsife.usc.edu\\\/physics\\\/#website\",\"url\":\"https:\\\/\\\/dornsife.usc.edu\\\/physics\\\/\",\"name\":\"Department of Physics and Astronomy\",\"description\":\"USC Dornsife Department of Physics and Astronomy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dornsife.usc.edu\\\/physics\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Staff - Department of Physics and Astronomy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dornsife.usc.edu\/physics\/staff\/","og_locale":"en_US","og_type":"article","og_title":"Staff - Department of Physics and Astronomy","og_url":"https:\/\/dornsife.usc.edu\/physics\/staff\/","og_site_name":"Department of Physics and Astronomy","article_modified_time":"2024-09-17T17:04:20+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dornsife.usc.edu\/physics\/staff\/","url":"https:\/\/dornsife.usc.edu\/physics\/staff\/","name":"Staff - Department of Physics and Astronomy","isPartOf":{"@id":"https:\/\/dornsife.usc.edu\/physics\/#website"},"datePublished":"2023-04-12T18:49:20+00:00","dateModified":"2024-09-17T17:04:20+00:00","breadcrumb":{"@id":"https:\/\/dornsife.usc.edu\/physics\/staff\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dornsife.usc.edu\/physics\/staff\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dornsife.usc.edu\/physics\/staff\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dornsife.usc.edu\/physics\/"},{"@type":"ListItem","position":2,"name":"Staff"}]},{"@type":"WebSite","@id":"https:\/\/dornsife.usc.edu\/physics\/#website","url":"https:\/\/dornsife.usc.edu\/physics\/","name":"Department of Physics and Astronomy","description":"USC Dornsife Department of Physics and Astronomy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dornsife.usc.edu\/physics\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/dornsife.usc.edu\/physics\/wp-json\/wp\/v2\/pages\/1376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dornsife.usc.edu\/physics\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dornsife.usc.edu\/physics\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dornsife.usc.edu\/physics\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/dornsife.usc.edu\/physics\/wp-json\/wp\/v2\/comments?post=1376"}],"version-history":[{"count":11,"href":"https:\/\/dornsife.usc.edu\/physics\/wp-json\/wp\/v2\/pages\/1376\/revisions"}],"predecessor-version":[{"id":3574,"href":"https:\/\/dornsife.usc.edu\/physics\/wp-json\/wp\/v2\/pages\/1376\/revisions\/3574"}],"wp:attachment":[{"href":"https:\/\/dornsife.usc.edu\/physics\/wp-json\/wp\/v2\/media?parent=1376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}