{"id":495,"date":"2023-11-09T13:44:46","date_gmt":"2023-11-09T21:44:46","guid":{"rendered":"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/?page_id=495"},"modified":"2023-11-17T15:05:23","modified_gmt":"2023-11-17T23:05:23","slug":"angeles-waterfall","status":"publish","type":"page","link":"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/angeles-waterfall\/","title":{"rendered":"Angeles Waterfall"},"content":{"rendered":"\n\n  \n    \n\n\n\n\n\n\n<div\n  class=\"cc--component-container cc--rich-text \"\n\n  \n  \n  \n  \n  \n  \n  >\n  <div class=\"c--component c--rich-text\"\n    \n      >\n\n    \n      \n<div class=\"f--field f--wysiwyg\">\n\n    \n  <p><img decoding=\"async\" class=\"size-medium wp-image-310\" src=\"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/wp-content\/uploads\/sites\/403\/2023\/11\/Angeles_Waterfall_2.png\" sizes=\"(max-width: 300px) 100vw, 994px\" srcset=\"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/wp-content\/uploads\/sites\/403\/2023\/11\/Angeles_Waterfall_2.png 300w, https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/wp-content\/uploads\/sites\/403\/2023\/11\/Angeles_Waterfall_2.png 994w\" alt=\"Angeles Waterfall\" \/><\/p>\n<p><img decoding=\"async\" class=\"size-medium wp-image-310\" src=\"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/wp-content\/uploads\/sites\/403\/2023\/11\/Angeles_Waterfall_.png\" sizes=\"(max-width: 300px) 100vw, 994px\" srcset=\"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/wp-content\/uploads\/sites\/403\/2023\/11\/Angeles_Waterfall_.png 300w, https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/wp-content\/uploads\/sites\/403\/2023\/11\/Angeles_Waterfall_.png 994w\" alt=\"Angeles Waterfall\" \/><\/p>\n\n\n\n<\/div>\n\n\n  <\/div><\/div>\n\n\n\n          \n  \n    \n\n\n\n\n\n\n<div\n  class=\"cc--component-container cc--link-list \"\n\n  \n  \n  \n  \n  \n  \n  >\n  <div class=\"c--component c--link-list\"\n    \n      >\n\n    \n      <div class=\"header-container\">\n\n                  \n<div class=\"f--field f--section-title\">\n\n    \n  <h2>\n          List of cyanobacteria found at this site:\n      <\/h2>\n\n\n<\/div>\n                <\/div>\n  \n      <div class=\"links-container\">\n\n                        \n        \n          \n            <div class=\"column\">\n                <ul>\n                                                                  <li>\n                                \n<div class=\"f--field f--link\">\n\n    \n    \n  \n<a \n  class=\"link\"\n  href= https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/anabaena\/\n    aria-label=\"Read more about Anabaena\"  \n>\n    Anabaena \n  <svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 35 35\" enable-background=\"new 0 0 35 35\" width=\"25\" height=\"25\" xml:space=\"preserve\"><polygon fill-rule=\"evenodd\" clip-rule=\"evenodd\" fill=\"#000\" points=\"19.3,27.5 29.3,17.5,19.3,7.5 16.3,10.4 21.4,15.4 6.7,15.4 6.7,19.6 21.4,19.6 16.3,24.6 \"\/><\/svg>\n<\/a>\n\n\n<\/div>\n\n                                                    <\/li>\n                                                                                        <li>\n                                \n<div class=\"f--field f--link\">\n\n    \n    \n  \n<a \n  class=\"link\"\n  href= https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/angeles-waterfall\/\n    aria-label=\"Read more about Homoeothrix\"  \n>\n    Homoeothrix \n  <svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 35 35\" enable-background=\"new 0 0 35 35\" width=\"25\" height=\"25\" xml:space=\"preserve\"><polygon fill-rule=\"evenodd\" clip-rule=\"evenodd\" fill=\"#000\" points=\"19.3,27.5 29.3,17.5,19.3,7.5 16.3,10.4 21.4,15.4 6.7,15.4 6.7,19.6 21.4,19.6 16.3,24.6 \"\/><\/svg>\n<\/a>\n\n\n<\/div>\n\n                                                    <\/li>\n                                                                                        <li>\n                                \n<div class=\"f--field f--link\">\n\n    \n    \n  \n<a \n  class=\"link\"\n  href= https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/leptolyngbya\/\n    aria-label=\"Read more about Leptolyngbya\"  \n>\n    Leptolyngbya \n  <svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 35 35\" enable-background=\"new 0 0 35 35\" width=\"25\" height=\"25\" xml:space=\"preserve\"><polygon fill-rule=\"evenodd\" clip-rule=\"evenodd\" fill=\"#000\" points=\"19.3,27.5 29.3,17.5,19.3,7.5 16.3,10.4 21.4,15.4 6.7,15.4 6.7,19.6 21.4,19.6 16.3,24.6 \"\/><\/svg>\n<\/a>\n\n\n<\/div>\n\n                                                    <\/li>\n                                                          <\/ul>\n            <\/div>\n\n          \n          \n        \n          \n            <div class=\"column\">\n                <ul>\n                                                                  <li>\n                                \n<div class=\"f--field f--link\">\n\n    \n    \n  \n<a \n  class=\"link\"\n  href= https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/phormidium\/\n    aria-label=\"Read more about Phormidium\"  \n>\n    Phormidium \n  <svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 35 35\" enable-background=\"new 0 0 35 35\" width=\"25\" height=\"25\" xml:space=\"preserve\"><polygon fill-rule=\"evenodd\" clip-rule=\"evenodd\" fill=\"#000\" points=\"19.3,27.5 29.3,17.5,19.3,7.5 16.3,10.4 21.4,15.4 6.7,15.4 6.7,19.6 21.4,19.6 16.3,24.6 \"\/><\/svg>\n<\/a>\n\n\n<\/div>\n\n                                                    <\/li>\n                                                                                        <li>\n                                \n<div class=\"f--field f--link\">\n\n    \n    \n  \n<a \n  class=\"link\"\n  href= https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/spirulina\/\n    aria-label=\"Read more about Spirulina\"  \n>\n    Spirulina \n  <svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 35 35\" enable-background=\"new 0 0 35 35\" width=\"25\" height=\"25\" xml:space=\"preserve\"><polygon fill-rule=\"evenodd\" clip-rule=\"evenodd\" fill=\"#000\" points=\"19.3,27.5 29.3,17.5,19.3,7.5 16.3,10.4 21.4,15.4 6.7,15.4 6.7,19.6 21.4,19.6 16.3,24.6 \"\/><\/svg>\n<\/a>\n\n\n<\/div>\n\n                                                    <\/li>\n                                                          <\/ul>\n            <\/div>\n\n          \n          \n        \n\n\n\n    <\/div>\n  \n\n  <\/div><\/div>\n\n\n\n\n\n                \n  \n    \n\n\n\n\n\n\n<div\n  class=\"cc--component-container cc--image-gallery \"\n\n  \n  \n  \n  \n  \n  \n  >\n  <div class=\"c--component c--image-gallery\"\n    \n      >\n\n    \n  <div class=\"inner-wrapper\">\n\n      <div class=\"text-container\">\n                  \n<div class=\"f--field f--section-title\">\n\n    \n  <h2>\n          Samples from Angeles Waterfall\n      <\/h2>\n\n\n<\/div>\n          <\/div>\n    \n      <div id=\"gallery-1710696068\" class=\"gallery-container\">\n\n      <div class=\"swiper images\">\n        <div class=\"swiper-wrapper\">\n                                    <div class=\"swiper-slide\">\n                                      \n<div class=\"f--field f--image\">\n\n    \n    \n    \n    \n    \n    \n              \n      <img\n                            data-src=\"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/wp-content\/uploads\/sites\/403\/2023\/11\/6464-760x432.jpg\"\n                    data-sizes=\"(min-width:1200px) 75vw, (min-width:768px) 83vw, 100vw\"          class=\"lazyload\"\n        \n                  alt=\"Samples from Angeles Waterfall\"\n        \n        \n                                      \/>\n\n    \n    \n  \n  \n\n<\/div>\n                              <\/div>\n                                                <div class=\"swiper-slide\">\n                                      \n<div class=\"f--field f--image\">\n\n    \n    \n    \n    \n    \n    \n              \n      <img\n                            data-src=\"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/wp-content\/uploads\/sites\/403\/2023\/11\/6463-761x432.jpg\"\n                    data-sizes=\"(min-width:1200px) 75vw, (min-width:768px) 83vw, 100vw\"          class=\"lazyload\"\n        \n                  alt=\"Samples from Angeles Waterfall\"\n        \n        \n                                      \/>\n\n    \n    \n  \n  \n\n<\/div>\n                              <\/div>\n                                                <div class=\"swiper-slide\">\n                                      \n<div class=\"f--field f--image\">\n\n    \n    \n    \n    \n    \n    \n              \n      <img\n                            data-src=\"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/wp-content\/uploads\/sites\/403\/2023\/11\/6462-761x432.jpg\"\n                    data-sizes=\"(min-width:1200px) 75vw, (min-width:768px) 83vw, 100vw\"          class=\"lazyload\"\n        \n                  alt=\"Samples from Angeles Waterfall\"\n        \n        \n                                      \/>\n\n    \n    \n  \n  \n\n<\/div>\n                              <\/div>\n                                                <div class=\"swiper-slide\">\n                                      \n<div class=\"f--field f--image\">\n\n    \n    \n    \n    \n    \n    \n              \n      <img\n                            data-src=\"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/wp-content\/uploads\/sites\/403\/2023\/11\/6461-761x432.jpg\"\n                    data-sizes=\"(min-width:1200px) 75vw, (min-width:768px) 83vw, 100vw\"          class=\"lazyload\"\n        \n                  alt=\"Samples from Angeles Waterfall\"\n        \n        \n                                      \/>\n\n    \n    \n  \n  \n\n<\/div>\n                              <\/div>\n                              <\/div>\n      <\/div>\n\n      <div class=\"swiper captions\">\n        <div class=\"controls-container\">\n          <button class=\"button-prev\" aria-label=\"Previous Image\">\n            <svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"\n            x=\"0px\" y=\"0px\" viewBox=\"0 0 35 35\" enable-background=\"new 0 0 35 35\" xml:space=\"preserve\">\n            <polygon fill-rule=\"evenodd\" clip-rule=\"evenodd\" fill=\"#000\" points=\"15.7,27.5 5.7,17.5 \n            15.7,7.5 18.7,10.4 13.6,15.4 28.3,15.4 28.3,19.6 13.6,19.6 18.7,24.6 \"\/>\n            <\/svg>\n          <\/button>\n          <button class=\"button-next\" aria-label=\"Next Image\">\n            <svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"\n\t x=\"0px\" y=\"0px\" viewBox=\"0 0 35 35\" enable-background=\"new 0 0 35 35\" xml:space=\"preserve\"><polygon fill-rule=\"evenodd\" clip-rule=\"evenodd\" fill=\"#000\" points=\"19.3,27.5 29.3,17.5 \n\t19.3,7.5 16.3,10.4 21.4,15.4 6.7,15.4 6.7,19.6 21.4,19.6 16.3,24.6 \"\/>\n<\/svg>\n          <\/button>\n        <\/div>\n\n        <div class=\"swiper-wrapper\">\n                                    <div class=\"swiper-slide\">\n                                  <div class=\"slide-caption\">\n                        \n<div class=\"f--field f--description\">\n\n    \n  <p>(1\/4) Leptolyngbya<\/p>\n\n\n\n<\/div>\n                  <\/div>\n                              <\/div>\n                                                <div class=\"swiper-slide\">\n                                  <div class=\"slide-caption\">\n                        \n<div class=\"f--field f--description\">\n\n    \n  <p>(2\/4) Phormidium<\/p>\n\n\n\n<\/div>\n                  <\/div>\n                              <\/div>\n                                                <div class=\"swiper-slide\">\n                                  <div class=\"slide-caption\">\n                        \n<div class=\"f--field f--description\">\n\n    \n  <p>(3\/4) Phormidium<\/p>\n\n\n\n<\/div>\n                  <\/div>\n                              <\/div>\n                                                <div class=\"swiper-slide\">\n                                  <div class=\"slide-caption\">\n                        \n<div class=\"f--field f--description\">\n\n    \n  <p>(4\/4) Phormidium and Spirulina<\/p>\n\n\n\n<\/div>\n                  <\/div>\n                              <\/div>\n                              <\/div>\n\n      <\/div>\n\n\n    <\/div>\n  \n  <\/div>\n\n\n  <\/div><\/div>\n\n\n  \n    \n\n\n\n\n\n\n<div\n  class=\"cc--component-container cc--spacer \"\n\n  \n  \n  \n  \n  \n  \n  >\n  <div class=\"c--component c--spacer\"\n    \n      >\n\n    \n\n  <\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":548,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-495","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Angeles Waterfall - Cyanobacteria Guide<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/angeles-waterfall\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Angeles Waterfall - Cyanobacteria Guide\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/angeles-waterfall\/\" \/>\n<meta property=\"og:site_name\" content=\"Cyanobacteria Guide\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-17T23:05:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dornsife.usc.edu\\\/cyanobacteria-guide\\\/angeles-waterfall\\\/\",\"url\":\"https:\\\/\\\/dornsife.usc.edu\\\/cyanobacteria-guide\\\/angeles-waterfall\\\/\",\"name\":\"Angeles Waterfall - Cyanobacteria Guide\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dornsife.usc.edu\\\/cyanobacteria-guide\\\/#website\"},\"datePublished\":\"2023-11-09T21:44:46+00:00\",\"dateModified\":\"2023-11-17T23:05:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dornsife.usc.edu\\\/cyanobacteria-guide\\\/angeles-waterfall\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dornsife.usc.edu\\\/cyanobacteria-guide\\\/angeles-waterfall\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dornsife.usc.edu\\\/cyanobacteria-guide\\\/angeles-waterfall\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dornsife.usc.edu\\\/cyanobacteria-guide\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Angeles Waterfall\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dornsife.usc.edu\\\/cyanobacteria-guide\\\/#website\",\"url\":\"https:\\\/\\\/dornsife.usc.edu\\\/cyanobacteria-guide\\\/\",\"name\":\"Cyanobacteria Guide\",\"description\":\"USC Dornsife Cyanobacteria Guide\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dornsife.usc.edu\\\/cyanobacteria-guide\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Angeles Waterfall - Cyanobacteria Guide","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/angeles-waterfall\/","og_locale":"en_US","og_type":"article","og_title":"Angeles Waterfall - Cyanobacteria Guide","og_url":"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/angeles-waterfall\/","og_site_name":"Cyanobacteria Guide","article_modified_time":"2023-11-17T23:05:23+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/angeles-waterfall\/","url":"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/angeles-waterfall\/","name":"Angeles Waterfall - Cyanobacteria Guide","isPartOf":{"@id":"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/#website"},"datePublished":"2023-11-09T21:44:46+00:00","dateModified":"2023-11-17T23:05:23+00:00","breadcrumb":{"@id":"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/angeles-waterfall\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/angeles-waterfall\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/angeles-waterfall\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/"},{"@type":"ListItem","position":2,"name":"Angeles Waterfall"}]},{"@type":"WebSite","@id":"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/#website","url":"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/","name":"Cyanobacteria Guide","description":"USC Dornsife Cyanobacteria Guide","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/wp-json\/wp\/v2\/pages\/495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/wp-json\/wp\/v2\/users\/548"}],"replies":[{"embeddable":true,"href":"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/wp-json\/wp\/v2\/comments?post=495"}],"version-history":[{"count":35,"href":"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/wp-json\/wp\/v2\/pages\/495\/revisions"}],"predecessor-version":[{"id":1513,"href":"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/wp-json\/wp\/v2\/pages\/495\/revisions\/1513"}],"wp:attachment":[{"href":"https:\/\/dornsife.usc.edu\/cyanobacteria-guide\/wp-json\/wp\/v2\/media?parent=495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}