{"id":522,"date":"2022-11-05T01:10:03","date_gmt":"2022-11-05T01:10:03","guid":{"rendered":"https:\/\/dornsife.usc.edu\/components\/?page_id=522"},"modified":"2022-12-15T00:52:59","modified_gmt":"2022-12-15T00:52:59","slug":"contact-details","status":"publish","type":"page","link":"https:\/\/dornsife.usc.edu\/components\/contact-details\/","title":{"rendered":"Contact Details"},"content":{"rendered":"  \n    \n\n\n\n\n\n\n<div\n  class=\"cc--component-container cc--spacer \"\n\n  \n  \n  \n  \n  \n  \n  >\n  <div class=\"c--component c--spacer\"\n    \n      >\n\n    \n\n  <\/div><\/div>\n\n\n\n\n  \n    \n\n\n\n\n\n\n<div\n  class=\"cc--component-container cc--rich-text \"\n\n  \n  \n  \n  \n  \n  \n  >\n  <div class=\"c--component c--rich-text\"\n    \n      >\n\n    \n      \n<div class=\"f--field f--wysiwyg\">\n\n    \n  <p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-16x9_1280 wp-image-512\" src=\"https:\/\/dornsife.usc.edu\/components\/wp-content\/uploads\/sites\/33\/2022\/11\/contact_details-1-1280x720.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/dornsife.usc.edu\/components\/wp-content\/uploads\/sites\/33\/2022\/11\/contact_details-1-1280x720.jpg 1280w, https:\/\/dornsife.usc.edu\/components\/wp-content\/uploads\/sites\/33\/2022\/11\/contact_details-1-300x169.jpg 300w, https:\/\/dornsife.usc.edu\/components\/wp-content\/uploads\/sites\/33\/2022\/11\/contact_details-1-768x432.jpg 768w, https:\/\/dornsife.usc.edu\/components\/wp-content\/uploads\/sites\/33\/2022\/11\/contact_details-1-1920x1080.jpg 1920w, https:\/\/dornsife.usc.edu\/components\/wp-content\/uploads\/sites\/33\/2022\/11\/contact_details-1.jpg 1948w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n\n\n\n<\/div>\n\n\n  <\/div><\/div>\n\n\n\n\n  \n    \n\n\n\n\n\n\n<div\n  class=\"cc--component-container cc--rich-text \"\n\n  \n  \n  \n  \n  \n  \n  >\n  <div class=\"c--component c--rich-text\"\n    \n      >\n\n    \n      \n<div class=\"f--field f--wysiwyg\">\n\n    \n  <h3>How to Video<\/h3>\n<div class=\"video-embed\"><iframe loading=\"lazy\" title=\"Contact Details\" src=\"https:\/\/player.vimeo.com\/video\/778311072?h=df219df451&amp;dnt=1&amp;app_id=122963\" width=\"500\" height=\"273\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write\"><\/iframe><\/div>\n\n\n\n<\/div>\n\n\n  <\/div><\/div>\n\n\n  \n    \n\n\n\n\n\n\n<div\n  class=\"cc--component-container cc--spacer \"\n\n  \n  \n  \n  \n  \n  \n  >\n  <div class=\"c--component c--spacer\"\n    \n      >\n\n    \n\n  <\/div><\/div>\n\n\n      \n  \n    \n\n\n\n\n\n\n<div\n  class=\"cc--component-container cc--contact-details \"\n\n  \n  \n  \n  \n  \n  \n  >\n  <div class=\"c--component c--contact-details\"\n    \n      >\n\n    \n  <div class=\"inner-wrapper\">\n\n          <div class=\"header-container\">\n\n                      \n<div class=\"f--field f--section-title\">\n\n    \n  <h2>\n          Contact Details\n      <\/h2>\n\n\n<\/div>\n        \n                      \n<div class=\"f--field f--link\">\n\n    \n    \n  \n<a \n  class=\"link\"\n  href= https:\/\/dornsife.usc.edu\/website-project\n    aria-label=\"Read more about Dornsife Web Project\"  \n>\n    Dornsife Web Project \n  <svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 35 35\" enable-background=\"new 0 0 35 35\" width=\"25\" height=\"25\" xml:space=\"preserve\"><polygon fill-rule=\"evenodd\" clip-rule=\"evenodd\" fill=\"#000\" points=\"19.3,27.5 29.3,17.5,19.3,7.5 16.3,10.4 21.4,15.4 6.7,15.4 6.7,19.6 21.4,19.6 16.3,24.6 \"\/><\/svg>\n<\/a>\n\n\n<\/div>\n        \n      <\/div>\n    \n    \n      <div class=\"contacts-container\">\n\n        \n                      <div class=\"contact-card\">\n\n                              <h3>Contact Us<\/h3>\n              \n                                  \n<div class=\"f--field f--description\">\n\n    \n  <p>If you have additional questions, please email<\/p>\n\n\n\n<\/div>\n              \n              \n                              <div class=\"f--email\">\n                  <a href=\"mailto:webproject@dornsife.usc.edu.\">webproject@dornsife.usc.edu.<\/a>\n                <\/div>\n              \n            <\/div>\n                    \n                      <div class=\"contact-card\">\n\n                              <h3>USC Dornsife Business Office<\/h3>\n              \n                                  \n<div class=\"f--field f--description\">\n\n    \n  <p>3616 Trousdale Parkway, AHF 108<br \/>\nLos Angeles, CA 90089-0376<\/p>\n\n\n\n<\/div>\n              \n                              <div class=\"f--phone\">\n                  <a href=\"tel:(213) 740-4940\">(213) 740-4940<\/a>\n                <\/div>\n              \n                              <div class=\"f--email\">\n                  <a href=\"mailto:business@dornsife.usc.edu\">business@dornsife.usc.edu<\/a>\n                <\/div>\n              \n            <\/div>\n                    \n                      <div class=\"contact-card\">\n\n                              <h3>Contact Card 3<\/h3>\n              \n                                  \n<div class=\"f--field f--description\">\n\n    \n  <p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Curabitur gravida nisl nunc. Ut vel neque dapibus, feugiat ex et, tincidunt dolor. In interdum sollicitudin lectus vel rutrum.<\/p>\n\n\n\n<\/div>\n              \n              \n              \n            <\/div>\n                    \n      <\/div>\n\n        \n     \n    \n  <\/div>\n\n\n  <\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-522","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contact Details - Wordpress CMS Components<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact Details - Wordpress CMS Components\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dornsife.usc.edu\/components\/contact-details\/\" \/>\n<meta property=\"og:site_name\" content=\"Wordpress CMS Components\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-15T00:52:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dornsife.usc.edu\\\/components\\\/contact-details\\\/\",\"url\":\"https:\\\/\\\/dornsife.usc.edu\\\/components\\\/contact-details\\\/\",\"name\":\"Contact Details - Wordpress CMS Components\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dornsife.usc.edu\\\/components\\\/#website\"},\"datePublished\":\"2022-11-05T01:10:03+00:00\",\"dateModified\":\"2022-12-15T00:52:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dornsife.usc.edu\\\/components\\\/contact-details\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dornsife.usc.edu\\\/components\\\/contact-details\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dornsife.usc.edu\\\/components\\\/contact-details\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dornsife.usc.edu\\\/components\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact Details\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dornsife.usc.edu\\\/components\\\/#website\",\"url\":\"https:\\\/\\\/dornsife.usc.edu\\\/components\\\/\",\"name\":\"Wordpress CMS Components\",\"description\":\"CMS components\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dornsife.usc.edu\\\/components\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact Details - Wordpress CMS Components","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Contact Details - Wordpress CMS Components","og_url":"https:\/\/dornsife.usc.edu\/components\/contact-details\/","og_site_name":"Wordpress CMS Components","article_modified_time":"2022-12-15T00:52:59+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dornsife.usc.edu\/components\/contact-details\/","url":"https:\/\/dornsife.usc.edu\/components\/contact-details\/","name":"Contact Details - Wordpress CMS Components","isPartOf":{"@id":"https:\/\/dornsife.usc.edu\/components\/#website"},"datePublished":"2022-11-05T01:10:03+00:00","dateModified":"2022-12-15T00:52:59+00:00","breadcrumb":{"@id":"https:\/\/dornsife.usc.edu\/components\/contact-details\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dornsife.usc.edu\/components\/contact-details\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dornsife.usc.edu\/components\/contact-details\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dornsife.usc.edu\/components\/"},{"@type":"ListItem","position":2,"name":"Contact Details"}]},{"@type":"WebSite","@id":"https:\/\/dornsife.usc.edu\/components\/#website","url":"https:\/\/dornsife.usc.edu\/components\/","name":"Wordpress CMS Components","description":"CMS components","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dornsife.usc.edu\/components\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/dornsife.usc.edu\/components\/wp-json\/wp\/v2\/pages\/522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dornsife.usc.edu\/components\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dornsife.usc.edu\/components\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dornsife.usc.edu\/components\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dornsife.usc.edu\/components\/wp-json\/wp\/v2\/comments?post=522"}],"version-history":[{"count":9,"href":"https:\/\/dornsife.usc.edu\/components\/wp-json\/wp\/v2\/pages\/522\/revisions"}],"predecessor-version":[{"id":1966,"href":"https:\/\/dornsife.usc.edu\/components\/wp-json\/wp\/v2\/pages\/522\/revisions\/1966"}],"wp:attachment":[{"href":"https:\/\/dornsife.usc.edu\/components\/wp-json\/wp\/v2\/media?parent=522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}